{"id":7884,"date":"2017-05-05T15:53:58","date_gmt":"2017-05-05T13:53:58","guid":{"rendered":"http:\/\/rosstal-handball.de\/?p=7884"},"modified":"2017-05-05T15:53:58","modified_gmt":"2017-05-05T13:53:58","slug":"vorbericht-zwei-endspiele","status":"publish","type":"post","link":"https:\/\/tsv-rosstal.de\/handball\/2017\/05\/05\/vorbericht-zwei-endspiele\/","title":{"rendered":"Vorbericht: Zwei Endspiele"},"content":{"rendered":"<p>Das hatte man sich anders vorgestellt. Nach dem \u00fcberzeugenden Kantersieg gegen die HG Ansbach und dem damit einhergehenden Nichtabstiegsplatz wollte die \u201eErschde\u201c eigentlich in den darauffolgenden Partien nachlegen. Stattdessen setzte es zuletzt drei bittere Niederlagen in Folge, durch die man nun, kurz vor dem Saisonfinale, mit dem R\u00fccken zur Wand steht. Wenn am <strong>morgigen Abend um 19:30 Uhr<\/strong> der Anpfiff in der Mittelschulhalle ert\u00f6nt, haben die Ro\u00dftaler Handballer das erste von zwei absoluten Endspielen direkt vor der Brust. Allein zwei Siege k\u00f6nnen die Mannschaft des scheidenden Trainers Wolfgang Schmidt jetzt noch retten, und das auch nur, wenn die Konkurrenz mitspielt. Vor allem auf Niederlagen des TV Erlangen Bruck II und des TV Helmbrechts ist man angewiesen, um immerhin den zur Relegation berechtigenden 10. Tabellenplatz zu erreichen.<br \/>\nAusgerechnet in dieser brisanten Situation kommt mit dem Klassenprimus und designierten Bayernliga-Aufsteiger das wohl schwerste Kaliber der laufenden Saison. Der <strong>TSV 2000 Rothenburg<\/strong> holte in der R\u00fcckrunde 20 von 22 m\u00f6glichen Punkten und lie\u00df zuletzt nie einen Zweifel daran, dass sie den Wiederaufstieg in Bayerns h\u00f6chste Spielklasse nach zwei Jahren Abstinenz endlich bewerkstelligen k\u00f6nnen. Das Team um Trainer Csaba Sz\u00fccs, seinerseits ehemaliger slowakischer Nationalspieler und seit Jahren erfolgreicher Trainer in fr\u00e4nkischen Gefilden, verf\u00fcgt \u00fcber eine k\u00f6rperlich robuste Abwehr, die hinter sich mit Andreas Amann den wohl besten Torh\u00fcter der Landesliga wei\u00df. Im Angriff haben die Tauberst\u00e4dter mit Neuzugang Ivan Scaramuca, Philipp Schemm sowie Nedim Jasarevic drei wurfgewaltige Spieler in ihren Reihen, auf die sich die Ro\u00dftaler Deckung unbedingt einstellen muss. Der Gastgeber darf wohl kaum mit Geschenken aus dem mittelalterlichen Touristenst\u00e4dtchen rechnen. Schlie\u00dflich hat sich der TSV bereits in Spiel eins nach dem eingefahrenen Aufstieg in Ansbach nicht gerade mit Ruhm bekleckert und wird wohl das n\u00e4chste prestigegeladene mittelfr\u00e4nkische Derby unbedingt f\u00fcr sich entscheiden wollen.<br \/>\nF\u00fcr die \u201eErschde\u201c gilt es darum, die \u00c4rmel hochzukrempeln und noch einmal alles zu geben, wenngleich die Vorzeichen zweifelsfrei nicht gut stehen. Doch wie hei\u00dft es so sch\u00f6n: Totgesagte leben l\u00e4nger!<br \/>\nEs ist zur Tradition geworden, dass sich die \u201eErschde\u201c zum Saisonende bei all seinen treuen Fans bedankt, und so sind am Samstag ab der Halbzeit wie gewohnt alle Getr\u00e4nke frei. Auf die Zuschauer kommt es vielleicht im Saisonendspurt noch einmal an. Gebt ei letztes Mal alles, um das Unm\u00f6gliche doch noch m\u00f6glich zu machen.<br \/>\n<em>Bericht: Manuel Erben<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das hatte man sich anders vorgestellt. Nach dem \u00fcberzeugenden Kantersieg gegen die HG Ansbach und dem damit einhergehenden Nichtabstiegsplatz wollte die \u201eErschde\u201c eigentlich in den darauffolgenden Partien nachlegen. Stattdessen setzte es zuletzt drei bittere Niederlagen in Folge, durch die man nun, kurz vor dem Saisonfinale, mit dem R\u00fccken zur Wand steht. Wenn am morgigen Abend [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-7884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/tsv-rosstal.de\/handball\/wp-json\/wp\/v2\/posts\/7884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsv-rosstal.de\/handball\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsv-rosstal.de\/handball\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsv-rosstal.de\/handball\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tsv-rosstal.de\/handball\/wp-json\/wp\/v2\/comments?post=7884"}],"version-history":[{"count":0,"href":"https:\/\/tsv-rosstal.de\/handball\/wp-json\/wp\/v2\/posts\/7884\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tsv-rosstal.de\/handball\/wp-json\/wp\/v2\/media\/7885"}],"wp:attachment":[{"href":"https:\/\/tsv-rosstal.de\/handball\/wp-json\/wp\/v2\/media?parent=7884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsv-rosstal.de\/handball\/wp-json\/wp\/v2\/categories?post=7884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsv-rosstal.de\/handball\/wp-json\/wp\/v2\/tags?post=7884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}